{"id":18,"date":"2020-02-10T05:28:56","date_gmt":"2020-02-10T05:28:56","guid":{"rendered":"http:\/\/temporal.cooperativadevinaixa.cat\/finalitzar-comanda\/"},"modified":"2020-02-10T05:44:04","modified_gmt":"2020-02-10T05:44:04","slug":"finalizar-compra","status":"publish","type":"page","link":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/","title":{"rendered":"Finalizar compra"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finalizar compra - Cooperativa de Vinaixa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finalizar compra - Cooperativa de Vinaixa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperativa de Vinaixa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/coop.vinaixa\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-10T05:44:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OlideVinaixa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/finalizar-compra\\\/\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/finalizar-compra\\\/\",\"name\":\"Finalizar compra - Cooperativa de Vinaixa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#website\"},\"datePublished\":\"2020-02-10T05:28:56+00:00\",\"dateModified\":\"2020-02-10T05:44:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/finalizar-compra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/finalizar-compra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/finalizar-compra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finalizar compra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/\",\"name\":\"Cooperativa de Vinaixa\",\"description\":\"Des de l&#039;any 1920 per oferir els millors productes nascuts de la nostra terra i t\u00e9 en l&#039;oli d&#039;oliva verge extra el seu m\u00e0xim exponent.\",\"publisher\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#organization\",\"name\":\"Cooperativa de Vinaixa\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cooperativa-vinaixa-logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cooperativa-vinaixa-logo-1.jpg\",\"width\":324,\"height\":294,\"caption\":\"Cooperativa de Vinaixa\"},\"image\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/coop.vinaixa\",\"https:\\\/\\\/x.com\\\/OlideVinaixa\",\"https:\\\/\\\/www.instagram.com\\\/cooperativadevinaixa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finalizar compra - Cooperativa de Vinaixa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/","og_locale":"es_ES","og_type":"article","og_title":"Finalizar compra - Cooperativa de Vinaixa","og_url":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/","og_site_name":"Cooperativa de Vinaixa","article_publisher":"https:\/\/www.facebook.com\/coop.vinaixa","article_modified_time":"2020-02-10T05:44:04+00:00","twitter_card":"summary_large_image","twitter_site":"@OlideVinaixa","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/","url":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/","name":"Finalizar compra - Cooperativa de Vinaixa","isPartOf":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#website"},"datePublished":"2020-02-10T05:28:56+00:00","dateModified":"2020-02-10T05:44:04+00:00","breadcrumb":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/finalizar-compra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jelly2.tllmediasolutions.es\/es\/"},{"@type":"ListItem","position":2,"name":"Finalizar compra"}]},{"@type":"WebSite","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#website","url":"https:\/\/jelly2.tllmediasolutions.es\/es\/","name":"Cooperativa de Vinaixa","description":"Des de l&#039;any 1920 per oferir els millors productes nascuts de la nostra terra i t\u00e9 en l&#039;oli d&#039;oliva verge extra el seu m\u00e0xim exponent.","publisher":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jelly2.tllmediasolutions.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#organization","name":"Cooperativa de Vinaixa","url":"https:\/\/jelly2.tllmediasolutions.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2020\/02\/cooperativa-vinaixa-logo-1.jpg","contentUrl":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2020\/02\/cooperativa-vinaixa-logo-1.jpg","width":324,"height":294,"caption":"Cooperativa de Vinaixa"},"image":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/coop.vinaixa","https:\/\/x.com\/OlideVinaixa","https:\/\/www.instagram.com\/cooperativadevinaixa\/"]}]}},"_links":{"self":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":0,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"wp:attachment":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}