{"id":818,"date":"2020-03-06T06:29:45","date_gmt":"2020-03-06T06:29:45","guid":{"rendered":"http:\/\/temporal.cooperativadevinaixa.cat\/producte\/oli-verd-oli-doliva-verge-extra-garrafa-vidre-5-l\/"},"modified":"2026-04-11T00:03:15","modified_gmt":"2026-04-11T00:03:15","slug":"aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l","status":"publish","type":"product","link":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/","title":{"rendered":"Aceite de Oliva Virgen Extra &#8211; Garrafa cristal 5 L"},"content":{"rendered":"<p>Aceite de Oliva Virgen Extra categor\u00eda superior de la zona del Valle de Vinaixa, obtenido directamente de\u00a0<b>olivas arbequinas<\/b>\u00a0de categor\u00eda superior mediante procedimientos mec\u00e1nicos de\u00a0<b>cosecha propia<\/b>.<\/p>\n<p>AOVE afrutado y suave, de una intensidad mediana y equilibrada.<\/p>\n<p><strong>Variedad<\/strong>: 100% arbequina.<\/p>\n<p><strong>Formato<\/strong>: 5 L<\/p>\n<p>Conservar en un lugar fresco y seco y en resguardo de la luz.<\/p>\n<p>Env\u00edos a domicilio. Consultadnos para transportes y cantidades especiales.<\/p>\n<p><img decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2021\/07\/venta-proximitat.png\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aceite de Oliva Virgen Extra categor\u00eda superior de la zona del Valle de Vinaixa, obtenido directamente de\u00a0olivas arbequinas\u00a0de categor\u00eda superior mediante procedimientos mec\u00e1nicos de\u00a0cosecha propia. AOVE afrutado y suave, de una intensidad mediana y equilibrada. Variedad: 100% arbequina. Formato: 5 L Conservar en un lugar fresco y seco y en resguardo de la luz. Env\u00edos [&hellip;]<\/p>\n","protected":false},"featured_media":2464,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[44],"product_tag":[],"class_list":{"0":"post-818","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aceite-virgen-extra","8":"first","9":"instock","10":"sale","11":"featured","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceite de Oliva Virgen Extra - Garrafa cristal 5 L - Cooperativa de Vinaixa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceite de Oliva Virgen Extra - Garrafa cristal 5 L - Cooperativa de Vinaixa\" \/>\n<meta property=\"og:description\" content=\"Aceite de Oliva Virgen Extra categor\u00eda superior de la zona del Valle de Vinaixa, obtenido directamente de\u00a0olivas arbequinas\u00a0de categor\u00eda superior mediante procedimientos mec\u00e1nicos de\u00a0cosecha propia. AOVE afrutado y suave, de una intensidad mediana y equilibrada. Variedad: 100% arbequina. Formato: 5 L Conservar en un lugar fresco y seco y en resguardo de la luz. Env\u00edos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperativa de Vinaixa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/coop.vinaixa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T00:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2022\/02\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OlideVinaixa\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/\",\"name\":\"Aceite de Oliva Virgen Extra - Garrafa cristal 5 L - Cooperativa de Vinaixa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg\",\"datePublished\":\"2020-03-06T06:29:45+00:00\",\"dateModified\":\"2026-04-11T00:03:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg\",\"contentUrl\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg\",\"width\":800,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/producto\\\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agrobotiga\",\"item\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/agrobotiga\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aceite de Oliva Virgen Extra &#8211; Garrafa cristal 5 L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/\",\"name\":\"Cooperativa de Vinaixa\",\"description\":\"Des de l&#039;any 1920 per oferir els millors productes nascuts de la nostra terra i t\u00e9 en l&#039;oli d&#039;oliva verge extra el seu m\u00e0xim exponent.\",\"publisher\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#organization\",\"name\":\"Cooperativa de Vinaixa\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cooperativa-vinaixa-logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cooperativa-vinaixa-logo-1.jpg\",\"width\":324,\"height\":294,\"caption\":\"Cooperativa de Vinaixa\"},\"image\":{\"@id\":\"https:\\\/\\\/jelly2.tllmediasolutions.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/coop.vinaixa\",\"https:\\\/\\\/x.com\\\/OlideVinaixa\",\"https:\\\/\\\/www.instagram.com\\\/cooperativadevinaixa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceite de Oliva Virgen Extra - Garrafa cristal 5 L - Cooperativa de Vinaixa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/","og_locale":"es_ES","og_type":"article","og_title":"Aceite de Oliva Virgen Extra - Garrafa cristal 5 L - Cooperativa de Vinaixa","og_description":"Aceite de Oliva Virgen Extra categor\u00eda superior de la zona del Valle de Vinaixa, obtenido directamente de\u00a0olivas arbequinas\u00a0de categor\u00eda superior mediante procedimientos mec\u00e1nicos de\u00a0cosecha propia. AOVE afrutado y suave, de una intensidad mediana y equilibrada. Variedad: 100% arbequina. Formato: 5 L Conservar en un lugar fresco y seco y en resguardo de la luz. Env\u00edos [&hellip;]","og_url":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/","og_site_name":"Cooperativa de Vinaixa","article_publisher":"https:\/\/www.facebook.com\/coop.vinaixa","article_modified_time":"2026-04-11T00:03:15+00:00","og_image":[{"width":800,"height":900,"url":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2022\/02\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@OlideVinaixa","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/","url":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/","name":"Aceite de Oliva Virgen Extra - Garrafa cristal 5 L - Cooperativa de Vinaixa","isPartOf":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/#primaryimage"},"image":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/#primaryimage"},"thumbnailUrl":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2022\/02\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg","datePublished":"2020-03-06T06:29:45+00:00","dateModified":"2026-04-11T00:03:15+00:00","breadcrumb":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/#primaryimage","url":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2022\/02\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg","contentUrl":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2022\/02\/oli-oliva-verge-extra-arbequina-5l-vidre.jpg","width":800,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/producto\/aceite-verde-aceite-de-oliva-virgen-extra-garrafa-cristal-5-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jelly2.tllmediasolutions.es\/es\/"},{"@type":"ListItem","position":2,"name":"Agrobotiga","item":"https:\/\/jelly2.tllmediasolutions.es\/agrobotiga\/"},{"@type":"ListItem","position":3,"name":"Aceite de Oliva Virgen Extra &#8211; Garrafa cristal 5 L"}]},{"@type":"WebSite","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#website","url":"https:\/\/jelly2.tllmediasolutions.es\/es\/","name":"Cooperativa de Vinaixa","description":"Des de l&#039;any 1920 per oferir els millors productes nascuts de la nostra terra i t\u00e9 en l&#039;oli d&#039;oliva verge extra el seu m\u00e0xim exponent.","publisher":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jelly2.tllmediasolutions.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#organization","name":"Cooperativa de Vinaixa","url":"https:\/\/jelly2.tllmediasolutions.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2020\/02\/cooperativa-vinaixa-logo-1.jpg","contentUrl":"https:\/\/jelly2.tllmediasolutions.es\/wp-content\/uploads\/2020\/02\/cooperativa-vinaixa-logo-1.jpg","width":324,"height":294,"caption":"Cooperativa de Vinaixa"},"image":{"@id":"https:\/\/jelly2.tllmediasolutions.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/coop.vinaixa","https:\/\/x.com\/OlideVinaixa","https:\/\/www.instagram.com\/cooperativadevinaixa\/"]}]}},"_links":{"self":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":1,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product\/818\/revisions"}],"predecessor-version":[{"id":1481,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product\/818\/revisions\/1481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/media\/2464"}],"wp:attachment":[{"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product_brand?post=818"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product_cat?post=818"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jelly2.tllmediasolutions.es\/es\/wp-json\/wp\/v2\/product_tag?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}